{"id":10041,"date":"2026-05-08T06:52:41","date_gmt":"2026-05-08T06:52:41","guid":{"rendered":"https:\/\/fundacionaturaparc.com\/?p=10041"},"modified":"2026-05-08T06:52:49","modified_gmt":"2026-05-08T06:52:49","slug":"fundacio-natura-parc-participa-con-cepad-en-el-macrosimulacro-marsec-26-en-el-dique-del-oeste-de-palma","status":"publish","type":"post","link":"https:\/\/fundacionaturaparc.com\/en\/fundacio-natura-parc-participa-con-cepad-en-el-macrosimulacro-marsec-26-en-el-dique-del-oeste-de-palma\/","title":{"rendered":"Fundaci\u00f3 Natura Parc participa con CEPAD en el macrosimulacro MARSEC-26 en el Dique del Oeste de Palma"},"content":{"rendered":"\n<p><strong>El departamento CEPAD de Fundaci\u00f3 Natura Parc colabor\u00f3 en un simulacro de emergencia sanitaria y riesgo biol\u00f3gico celebrado en el Puerto de Palma, junto a m\u00e1s de 20 organismos y cerca de 150 profesionales.<\/strong><\/p>\n\n\n\n<p>El pasado <strong>16 de abril<\/strong>, <strong>Fundaci\u00f3 Natura Parc<\/strong>, a trav\u00e9s de su departamento de animales dom\u00e9sticos <strong>CEPAD<\/strong>, particip\u00f3 en el <strong>macrosimulacro MARSEC-26<\/strong> celebrado en el <strong>Dique del Oeste de Palma<\/strong>, un ejercicio organizado por la <strong>Armada<\/strong> para evaluar la respuesta coordinada ante una posible <strong>emergencia sanitaria internacional<\/strong> en un entorno portuario.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.43-819x1024.jpeg\" alt=\"\" class=\"wp-image-10045\" srcset=\"https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.43-819x1024.jpeg 819w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.43-240x300.jpeg 240w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.43-768x960.jpeg 768w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.43.jpeg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<p>El operativo recre\u00f3 la llegada al <strong>Puerto de Palma<\/strong> de un buque procedente de \u00c1frica con un supuesto brote de <strong>virus Marburg<\/strong> a bordo. Este escenario de <strong>riesgo biol\u00f3gico<\/strong> contemplaba la presencia de varias personas afectadas, un cad\u00e1ver y un perro, lo que permiti\u00f3 activar un amplio dispositivo de <strong>coordinaci\u00f3n entre organismos de emergencia, sanidad, seguridad y protecci\u00f3n animal<\/strong>.<\/p>\n\n\n\n<p>En el ejercicio participaron <strong>m\u00e1s de 20 organizaciones<\/strong> y cerca de <strong>150 profesionales<\/strong>, entre ellos Sanidad Exterior, Protecci\u00f3n Civil de la Delegaci\u00f3n del Gobierno, el CCAES, la UME, el SAMU 061, Medicina Legal y Forense de Palma, el Hospital Son Espases, Servicios Funerarios, el Instituto Social de la Marina, el Ministerio de Agricultura, Pesca y Alimentaci\u00f3n y el Ministerio de Justicia de Baleares.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-819x1024.jpeg\" alt=\"\" class=\"wp-image-10042\" srcset=\"https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-819x1024.jpeg 819w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-240x300.jpeg 240w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-768x960.jpeg 768w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42.jpeg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<p>Desde <strong>Fundaci\u00f3 Natura Parc<\/strong>, la participaci\u00f3n del <strong>CEPAD<\/strong>, Centro de Protecci\u00f3n de Animales Dom\u00e9sticos, se enmarca en su labor de colaboraci\u00f3n en situaciones donde pueden verse implicados <strong>animales dom\u00e9sticos en emergencias<\/strong>, especialmente en contextos de <strong>riesgo sanitario, intervenci\u00f3n especial o posible contaminaci\u00f3n biol\u00f3gica<\/strong>.<\/p>\n\n\n\n<p>La presencia de un animal dentro del supuesto planteado permiti\u00f3 reforzar la importancia de contar con protocolos espec\u00edficos para garantizar la <strong>seguridad, el bienestar animal y la correcta coordinaci\u00f3n veterinaria<\/strong> en escenarios de alta complejidad. Este tipo de simulacros son fundamentales para mejorar la preparaci\u00f3n de los equipos y la capacidad de actuaci\u00f3n ante situaciones que afectan tanto a la <strong>salud p\u00fablica<\/strong> como a la <strong>protecci\u00f3n animal<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-2-1024x768.jpeg\" alt=\"buque contagiado\" class=\"wp-image-10048\" srcset=\"https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-2-1024x768.jpeg 1024w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-2-300x225.jpeg 300w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-2-768x576.jpeg 768w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-2-1536x1152.jpeg 1536w, https:\/\/fundacionaturaparc.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-08.39.42-2.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Con su participaci\u00f3n en este <strong>simulacro de emergencia en Palma<\/strong>, Fundaci\u00f3 Natura Parc reafirma su compromiso con el <strong>bienestar animal<\/strong>, la <strong>colaboraci\u00f3n institucional<\/strong>, la <strong>gesti\u00f3n responsable de animales<\/strong> <strong>dom\u00e9sticos<\/strong> y el servicio p\u00fablico ante situaciones de emergencia.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El departamento CEPAD de Fundaci\u00f3 Natura Parc colabor\u00f3 en un simulacro de emergencia sanitaria y riesgo biol\u00f3gico celebrado en el Puerto de Palma, junto a m\u00e1s de 20 organismos y cerca de 150 profesionales. El pasado 16 de abril, Fundaci\u00f3 Natura Parc, a trav\u00e9s de su departamento de animales dom\u00e9sticos CEPAD, particip\u00f3 en el macrosimulacro [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":10051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[150],"tags":[159,161,151,163,153,155,152,164,154,157,156,162],"class_list":["post-10041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cepad","tag-animales-domesticos-en-emergencias","tag-bienestar-animal","tag-buque-infectado","tag-centro-de-proteccion-de-animales-domesticos","tag-cepad","tag-dique-del-oeste-de-palma","tag-fundacio-natura-parc","tag-fundacio-natura-parc-participa-con-cepad-en-el-macrosimulacro-marsec-26-en-palma","tag-macrosimulacro-marsec-26","tag-riesgo-biologico","tag-simulacro-de-emergencia-sanitaria","tag-simulacro-en-palma"],"acf":[],"_links":{"self":[{"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/posts\/10041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/comments?post=10041"}],"version-history":[{"count":1,"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/posts\/10041\/revisions"}],"predecessor-version":[{"id":10054,"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/posts\/10041\/revisions\/10054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/media\/10051"}],"wp:attachment":[{"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/media?parent=10041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/categories?post=10041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionaturaparc.com\/en\/wp-json\/wp\/v2\/tags?post=10041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}